{"id":2069,"date":"2021-01-07T12:27:37","date_gmt":"2021-01-07T11:27:37","guid":{"rendered":"https:\/\/printendo.de\/blog\/?p=2069"},"modified":"2021-01-07T12:27:39","modified_gmt":"2021-01-07T11:27:39","slug":"auf-was-koennen-werbematerialien-gedruckt-werden-leitfaden-ueber-platten","status":"publish","type":"post","link":"https:\/\/printendo.de\/blog\/auf-was-koennen-werbematerialien-gedruckt-werden-leitfaden-ueber-platten\/","title":{"rendered":"Auf was k\u00f6nnen Werbematerialien gedruckt werden? Leitfaden \u00fcber Platten"},"content":{"rendered":"\n<p>Ob station\u00e4res Gesch\u00e4ft, Caf\u00e9 oder Messestand, alle diese Orte ben\u00f6tigen\neinen geeigneten Rahmen. Was meinen wir damit? Eine Ausstellung, erg\u00e4nzt durch\nWerbe- und Informationsmaterial, deren Aufgabe es sein wird, Beziehungen\nzwischen der Marke und dem Kunden aufzubauen, das Branding zu schmuggeln, zum\nAbschluss von Gesch\u00e4ften zu ermutigen sowie Informationen und Hilfestellung zu\ngeben, z.B. bei der Suche nach einem bestimmten Regal mit einer\nProduktkategorie.<\/p>\n\n\n\n<p>Banner, Schilder, St\u00e4nder und Poster setzen ihren Siegeszug an den Verkaufsstellen fort, indem sie zum Kauf eines zus\u00e4tzlichen Produkts anregen, \u00fcber Werbeaktionen informieren, zur Kasse oder in den Ladenbereich leiten, in dem sich die Bestseller befinden. Damit das Werbematerial diese Funktionen erf\u00fcllen kann, ist nicht nur ein qualitativ hochwertiger Druck, sondern auch ein richtig ausgew\u00e4hltes Material erforderlich, das dazu beitr\u00e4gt, alle Vorteile der Werbekreation herauszustellen. Wie lassen sich diese beiden Themen miteinander verbinden? Dies erfahren Sie in unserem Leitfaden \u00fcber harte Oberfl\u00e4chen und Platten.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u2611<\/strong><strong> KAPA Line Platten<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Die \u00dcbersicht \u00fcber harte Platten beginnt mit dem Produkt, das KAPA Line\ngenannt wird. Es handelt sich um eine d\u00fcnne Schaumstoffplatte mit patentierter\nSch\u00e4umungstechnologie, die f\u00fcr die Verwendung in Innenr\u00e4umen geeignet ist. Mit\nihr k\u00f6nnen leichte und dennoch haltbare Strukturen hergestellt werden, indem\nman sie in beliebige Formen fr\u00e4st und L\u00f6cher bohrt. Die Druckqualit\u00e4t auf der\nKAPA Line-Platte erm\u00f6glicht es, lebendige, saftige Farben zu erhalten.<\/p>\n\n\n\n<p>Anwendungsbeispiel:<\/p>\n\n\n\n<ul><li>Logos und Buchstaben<\/li><li>Werbetafeln und-schilder<\/li><li>Informationstafeln<\/li><li>Elemente von Messestand<\/li><li>Werbest\u00e4nder <\/li><\/ul>\n\n\n\n<p>Beispiele der Visualisierung:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"561\" height=\"425\" src=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/2-13.jpg\" alt=\"\" class=\"wp-image-2071\" srcset=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/2-13.jpg 561w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/2-13-300x227.jpg 300w\" sizes=\"(max-width: 561px) 100vw, 561px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u2611<\/strong><strong> Hohlkammerplatten<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Ein weiteres hartes Substrat ist eine r\u00f6hrenf\u00f6rmige Polypropylenplatte &#8211;\neine Kombination aus der Leichtigkeit von Wellpappe und der Haltbarkeit von\nKunststoff. Hohlkammerplatte kann frei bedruckt und in die gew\u00fcnschte Form\ngeschnitten werden. Sie wird f\u00fcr den Innen- und Au\u00dfenbereich geeignet sein. Das\nMaterial ist resistent gegen Feuchtigkeit und mechanische Besch\u00e4digungen und\ngleichzeitig anf\u00e4llig f\u00fcr die Verarbeitung.<\/p>\n\n\n\n<p>Anwendungsbeispiel:<\/p>\n\n\n\n<ul><li>Logos<\/li><li>Schachteln<\/li><li>f\u00fcr Hintergrundbeleuchtung<\/li><li>Elemente von Messestand<\/li><li>Werbest\u00e4nder<\/li><li>Werbetafeln<\/li><li>Raumdeko<\/li><\/ul>\n\n\n\n<p>Beispiele der Visualisierung:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"561\" height=\"425\" src=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/3-8.jpg\" alt=\"\" class=\"wp-image-2072\" srcset=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/3-8.jpg 561w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/3-8-300x227.jpg 300w\" sizes=\"(max-width: 561px) 100vw, 561px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u2611<\/strong><strong> PVC-Schaumplatte<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Unter den harten Platten finden wir auch eine leichte und montageeinfache\nPVC-Schaumplatte. Das Material ist formanf\u00e4llig, und die Bedruckung ist von\nbeiden Seiten m\u00f6glich. Dank des Einsatzes der direkten UV-Drucktechnologie \u2013 ist\ndas aufgetragene Design dauerhaft und beh\u00e4lt die intensiven Farben lange Zeit.<\/p>\n\n\n\n<p>Anwendungsbeispiel:<\/p>\n\n\n\n<ul><li>Werbetafeln<\/li><li>Ladenausstattung<\/li><li>Schl\u00fcsselanh\u00e4nger<\/li><li>Wobbler<\/li><li>Werbest\u00e4nder<\/li><li>Logos<\/li><\/ul>\n\n\n\n<p>Beispiele der Visualisierung:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/4-10-1024x576.jpg\" alt=\"\" class=\"wp-image-2073\" srcset=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/4-10.jpg 1024w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/4-10-300x169.jpg 300w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/4-10-768x432.jpg 768w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/4-10-585x329.jpg 585w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u2611<\/strong><strong> Harte PVC-Platte<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Eine andere Art ist die harte PVC-Platte. Das Material hat eine\ngleichm\u00e4\u00dfige, nicht por\u00f6se Struktur, die es widerstandsf\u00e4hig gegen Feuchtigkeit\nund Witterungseinfl\u00fcsse macht. Die Platte ist f\u00fcr den Innen- und Au\u00dfenbereich\ngeeignet, sie ist leicht, haltbar und einfach zu verarbeiten, und die direkte\nUV-Drucktechnik erm\u00f6glicht eine ausgezeichnete Farbwiedergabe.<\/p>\n\n\n\n<p>Anwendungsbeispiel:<\/p>\n\n\n\n<ul><li>Schilder<\/li><li>Werbetafeln<\/li><li>Informationstafeln<\/li><li>Ladenausstattung<\/li><li>3D-Elemente<\/li><li>St\u00e4nder<\/li><\/ul>\n\n\n\n<p>Beispiele der Visualisierung:<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/5-8-1024x768.jpg\" alt=\"\" class=\"wp-image-2074\" srcset=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/5-8.jpg 1024w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/5-8-300x225.jpg 300w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/5-8-768x576.jpg 768w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/5-8-585x439.jpg 585w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u2611<\/strong><strong> DIBOND-Platte<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Der Hit der letzten\nJahre unter den Platten ist DIBOND. Es wird mit patentierter Technologie\nhergestellt und verbindet die Leichtigkeit des Materials mit au\u00dfergew\u00f6hnlicher\nHaltbarkeit und Verarbeitungsf\u00e4higkeit. Die Platte hat einen PVC-Kern, der von\nAluminiumblechen (Vorder- und R\u00fcckseite) umgeben ist. DIBOND kann vollfarbig &#8211;\nauch beidseitig &#8211; bedruckt und entsprechend der Stanze in die gew\u00fcnschte Form\ngeschnitten werden. Werbematerialien aus DIBOND sind sowohl f\u00fcr den internen\nals auch f\u00fcr den externen Gebrauch geeignet.<\/p>\n\n\n\n<p>Anwendungsbeispiel:<\/p>\n\n\n\n<ul><li>Dekoelemente<\/li><li>Werbetafeln<\/li><li>Informationstafeln<\/li><li>Au\u00dfenschilder<\/li><li>Elemente eines Messestands<\/li><\/ul>\n\n\n\n<p>Beispiele der Visualisierung:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/6-4-1024x768.jpg\" alt=\"\" class=\"wp-image-2075\" srcset=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/6-4.jpg 1024w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/6-4-300x225.jpg 300w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/6-4-768x576.jpg 768w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/6-4-585x439.jpg 585w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u2611<\/strong><strong> HIPS-Platte<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Die HIPS-Platte ist ein weiteres hartes Material mit einem breiten\nAnwendungsspektrum. Dieses d\u00fcnne, leichte, aber dennoch starke und flexible\nPolystyrolmaterial eignet sich dank seiner hohen Witterungs- und\nSchadensbest\u00e4ndigkeit zur Schaffung komplexer Raumformen &#8211; innen oder au\u00dfen.\nDas Material kann in jede beliebige Form gefr\u00e4st und mit L\u00f6chern versehen\nwerden. Der UV-Druck auf der Hochglanzseite sorgt f\u00fcr einen einzigartigen\nEffekt und eine perfekte Farbwiedergabe.<\/p>\n\n\n\n<p>Anwendungsbeispiel:<\/p>\n\n\n\n<ul><li>Werbeschilder<\/li><li>Kassetten<\/li><li>Leuchtwerbung<\/li><li>Elemente der Ausstattung<\/li><li>3D-Buchstaben und Grafiken<\/li><li>Wobblers<\/li><\/ul>\n\n\n\n<p>Beispiele der Visualisierung:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/7-3-1024x768.jpg\" alt=\"\" class=\"wp-image-2076\" srcset=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/7-3.jpg 1024w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/7-3-300x225.jpg 300w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/7-3-768x576.jpg 768w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/7-3-585x439.jpg 585w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u2611<\/strong><strong> STADUR-Platte<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>STADUR ist eine harte Platte, mit \u00e4hnlicher Best\u00e4ndigkeit wie PVC, aber\nleichter und preislich g\u00fcnstiger. Der direkte UV-Druck erm\u00f6glicht es, ein dauerhaftes\nDesign in intensiven Farben und fotografischer Qualit\u00e4t zu erhalten. Trotz der\nbetr\u00e4chtlichen Dicke (8 mm) kann die Platte in jede beliebige Form gefr\u00e4st\nwerden, um z.B. r\u00e4umliche Logos, Zahlen oder Buchstaben zu erstellen.<\/p>\n\n\n\n<p>Anwendungsbeispiel:<\/p>\n\n\n\n<ul><li>Ladendekoration<\/li><li>Elemente von Messestand<\/li><li>Werbetafeln und -schilder<\/li><li>Elemente der Ausstattung<\/li><li>3D-Buchstaben und Grafiken<\/li><li>Logos<\/li><\/ul>\n\n\n\n<p>Beispiele der Visualisierung:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/8-5-1024x768.jpg\" alt=\"\" class=\"wp-image-2077\" srcset=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/8-5.jpg 1024w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/8-5-300x225.jpg 300w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/8-5-768x576.jpg 768w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/8-5-585x439.jpg 585w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u2611<\/strong><strong> PLEXIGLAS-Platte<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>Plexiglas-Platte ist ein Werbetr\u00e4ger mit einem breiten Anwendungsspektrum.\nDas Material ist in milchiger oder farbloser Ausf\u00fchrung erh\u00e4ltlich.\nPlexiglasplatten k\u00f6nnen in jede Form gebracht, auf jede Gr\u00f6\u00dfe zugeschnitten und\nmit L\u00f6chern versehen werden. Standard f\u00fcr Plexiglas ist ein einseitiger Druck\nmit wei\u00dfem Unterdruck. Durch den Verzicht auf die wei\u00dfe Farbe kann eine\nTransluzenz (der so genannte Glasfenstereffekt) erreicht werden, w\u00e4hrend die\nKombination von CMYK-Farben mit wei\u00dfem Unterdruck bei Belichtungsaufnahmen gut\nfunktioniert.<\/p>\n\n\n\n<p>Anwendungsbeispiel:<\/p>\n\n\n\n<ul><li>Elemente von Messestand<\/li><li>Werbetafeln<\/li><li>Informationsschilder<\/li><li>Plexist\u00e4nder<\/li><li>Werbest\u00e4nder<\/li><li>Elemente der Ladenausstattung<\/li><li>Beleuchtete W\u00e4nde<\/li><li>Spuckschutz (Kassen)<\/li><li>Raumdeko<\/li><\/ul>\n\n\n\n<p>Beispiele der Visualisierung:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/9-4-1024x768.jpg\" alt=\"\" class=\"wp-image-2078\" srcset=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/9-4.jpg 1024w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/9-4-300x225.jpg 300w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/9-4-768x576.jpg 768w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/9-4-585x439.jpg 585w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote\"><p>Gut zu wissen:<br><em>Bei printendo k\u00f6nnen Sie Ihre Plexiglasplatten in 4 Varianten bestellen: farblos, milchig, farblos unbedruckt mit Fr\u00e4sungen und L\u00f6chern, farblos ohne Druck und ohne Nachbearbeitung.<\/em><\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u2611<\/strong><strong> DISPA-Platte<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>DISPA-Platte ist die Wahl f\u00fcr alle, die nach umweltfreundlichen\nDruckl\u00f6sungen suchen. Das Material besteht zu 100% aus Papier und ist\nFSC-zertifiziert. Die Platte ist leicht, steif und stabil, gleichzeitig aber\nanf\u00e4llig f\u00fcr die Verarbeitung, und durch seine glatte, wei\u00dfe Oberfl\u00e4che lassen\nsich intensive, saftige Druckfarben erzielen. DISPA ist leicht zu montieren und\nzu demontieren und, was am wichtigsten ist, vollst\u00e4ndig bioabbaubar!<\/p>\n\n\n\n<p>Anwendungsbeispiel:<\/p>\n\n\n\n<ul><li>Werbetafeln f\u00fcr den Innenraum<\/li><li>Elemente f\u00fcr die Innenausstattung<\/li><li>Elemente von Messestand<\/li><li>St\u00e4nder<\/li><li>Raumdeko <\/li><\/ul>\n\n\n\n<p>Beispiele der Visualisierung:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"900\" height=\"630\" src=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/10-3.jpg\" alt=\"\" class=\"wp-image-2079\" srcset=\"https:\/\/printendo.de\/blog\/wp-content\/uploads\/10-3.jpg 900w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/10-3-300x210.jpg 300w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/10-3-768x538.jpg 768w, https:\/\/printendo.de\/blog\/wp-content\/uploads\/10-3-585x410.jpg 585w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Wie Sie sehen k\u00f6nnen, gibt es viele druckbare Materialien, und die\nHersteller konkurrieren miteinander bei der Entwicklung und Patentierung immer\nneuer Substrate. Es gibt viele Alternativen zum klassischen Papier, und die Art\ndes Rohmaterials wird auch durch die Art des Produktes bestimmt, das wir\nherstellen wollen &#8211; HIPS, STADUR oder DIBOND funktionieren gut, z.B. bei 3D-Buchstaben\nund Raumgrafiken, das Namensschild vor dem Betreten des B\u00fcros wird dagegen am\nbesten aussehen, wenn wir Plexiglas oder Metallmaterial w\u00e4hlen.<\/p>\n\n\n\n<p>Pr\u00fcfen Sie das komplette Angebot von Platten auf Printendo.de.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ob station\u00e4res Gesch\u00e4ft, Caf\u00e9 oder Messestand, alle diese Orte ben\u00f6tigen einen geeigneten Rahmen. Was meinen wir damit? Eine Ausstellung, erg\u00e4nzt durch Werbe- und Informationsmaterial, deren Aufgabe es sein wird, Beziehungen&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2070,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"categories":[38,39],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/posts\/2069"}],"collection":[{"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/comments?post=2069"}],"version-history":[{"count":1,"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/posts\/2069\/revisions"}],"predecessor-version":[{"id":2080,"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/posts\/2069\/revisions\/2080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/media\/2070"}],"wp:attachment":[{"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/media?parent=2069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/categories?post=2069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/printendo.de\/blog\/wp-json\/wp\/v2\/tags?post=2069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}